{"id":2821,"date":"2026-01-28T08:36:30","date_gmt":"2026-01-28T07:36:30","guid":{"rendered":"https:\/\/www.ilcambiamento.org\/wordpress\/?p=2821"},"modified":"2026-01-28T08:36:54","modified_gmt":"2026-01-28T07:36:54","slug":"dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi","status":"publish","type":"post","link":"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/","title":{"rendered":"Dice il proverbio &#8220;Chi per bugiardo \u00e8 conosciuto&#8230;&#8221; Sentiremo mai la verit\u00e0 prima o poi?"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Tombolo 26 gennaio 2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grazie all&#8217;interrogazione del nostro Gruppo anche stavolta il Sindaco viene clamorosamente smentito. Ogni volta lo stesso comunica alla cittadinanza come gli eventi siano rapidi ed improvvisi e non preventivabili. Anche su questa materia invece gli eventi erano non solo prevedibili, ma gi\u00e0 divenuti gravi fin dal 2021 come emerge dalla risposta del Sindaco stesso alla nostra interrogazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pubblichiamo cosa aveva detto il Sindaco il 16 dicembre e cosa invece \u00e8 costretto a rispondere dai documenti che emergono, i quali stabiliscono la colpevole inattivit\u00e0 di Valore Domani per ben 5 anni essendo iniziata la procedura di revoca della gestione degli impianti solo poche settimane fa, come comunicato dal Sindaco stesso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il Comune purtroppo non \u00e8 seguito e tutto \u00e8 lasciato al fato.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"714\" height=\"1024\" src=\"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/risposta-sindaco-1-impianti-sportivi-1.jpg?resize=714%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-2829\" srcset=\"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/risposta-sindaco-1-impianti-sportivi-1.jpg?resize=714%2C1024&amp;ssl=1 714w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/risposta-sindaco-1-impianti-sportivi-1.jpg?resize=209%2C300&amp;ssl=1 209w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/risposta-sindaco-1-impianti-sportivi-1.jpg?resize=768%2C1101&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/risposta-sindaco-1-impianti-sportivi-1.jpg?resize=167%2C240&amp;ssl=1 167w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/risposta-sindaco-1-impianti-sportivi-1.jpg?w=940&amp;ssl=1 940w\" sizes=\"auto, (max-width: 714px) 100vw, 714px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"663\" src=\"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/risposta-sindaco-2-impianti-sportivi.jpg?resize=740%2C663&#038;ssl=1\" alt=\"\" class=\"wp-image-2828\" style=\"aspect-ratio:1.1165109034267913;width:718px;height:auto\" srcset=\"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/risposta-sindaco-2-impianti-sportivi.jpg?w=920&amp;ssl=1 920w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/risposta-sindaco-2-impianti-sportivi.jpg?resize=300%2C269&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/risposta-sindaco-2-impianti-sportivi.jpg?resize=768%2C688&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/risposta-sindaco-2-impianti-sportivi.jpg?resize=240%2C215&amp;ssl=1 240w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"740\" src=\"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6430.png?resize=740%2C740&#038;ssl=1\" alt=\"\" class=\"wp-image-2825\" srcset=\"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6430.png?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6430.png?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6430.png?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6430.png?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6430.png?resize=240%2C240&amp;ssl=1 240w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6430.png?resize=1320%2C1320&amp;ssl=1 1320w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6430.png?w=1440&amp;ssl=1 1440w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"740\" src=\"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6431-1.jpg?resize=740%2C740&#038;ssl=1\" alt=\"\" class=\"wp-image-2826\" srcset=\"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6431-1.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6431-1.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6431-1.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6431-1.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6431-1.jpg?resize=240%2C240&amp;ssl=1 240w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6431-1.jpg?resize=1320%2C1320&amp;ssl=1 1320w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6431-1.jpg?w=1440&amp;ssl=1 1440w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"1008\" src=\"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6398.jpg?resize=740%2C1008&#038;ssl=1\" alt=\"\" class=\"wp-image-2830\" srcset=\"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6398.jpg?resize=752%2C1024&amp;ssl=1 752w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6398.jpg?resize=220%2C300&amp;ssl=1 220w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6398.jpg?resize=768%2C1046&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6398.jpg?resize=1128%2C1536&amp;ssl=1 1128w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6398.jpg?resize=176%2C240&amp;ssl=1 176w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/IMG_6398.jpg?w=1206&amp;ssl=1 1206w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Tombolo 26 gennaio 2026 Grazie all&#8217;interrogazione del nostro Gruppo anche stavolta il Sindaco viene clamorosamente smentito. Ogni [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[4],"tags":[47,28,46,45],"class_list":["post-2821","post","type-post","status-publish","format-standard","hentry","category-news","tag-bugie-di-frasson","tag-comune-di-tombolo","tag-impianti-sportivi-di-tombolo","tag-luca-frasson"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Tombolo 26 gennaio 2026 Grazie all&#039;interrogazione del nostro Gruppo anche stavolta il Sindaco viene clamorosamente smentito. Ogni volta lo stesso comunica alla cittadinanza come gli eventi siano rapidi ed improvvisi e non preventivabili. Anche su questa materia invece gli eventi erano non solo prevedibili, ma gi\u00e0 divenuti gravi fin dal 2021 come emerge dalla risposta\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"cambiamento\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD) - Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Dice il proverbio \u201cChi per bugiardo \u00e8 conosciuto\u2026\u201d Sentiremo mai la verit\u00e0 prima o poi? - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)\" \/>\n\t\t<meta property=\"og:description\" content=\"Tombolo 26 gennaio 2026 Grazie all&#039;interrogazione del nostro Gruppo anche stavolta il Sindaco viene clamorosamente smentito. Ogni volta lo stesso comunica alla cittadinanza come gli eventi siano rapidi ed improvvisi e non preventivabili. Anche su questa materia invece gli eventi erano non solo prevedibili, ma gi\u00e0 divenuti gravi fin dal 2021 come emerge dalla risposta\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-01-28T07:36:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-01-28T07:36:54+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/civicailcambiamento\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Dice il proverbio \u201cChi per bugiardo \u00e8 conosciuto\u2026\u201d Sentiremo mai la verit\u00e0 prima o poi? - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Tombolo 26 gennaio 2026 Grazie all&#039;interrogazione del nostro Gruppo anche stavolta il Sindaco viene clamorosamente smentito. Ogni volta lo stesso comunica alla cittadinanza come gli eventi siano rapidi ed improvvisi e non preventivabili. Anche su questa materia invece gli eventi erano non solo prevedibili, ma gi\u00e0 divenuti gravi fin dal 2021 come emerge dalla risposta\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\\\/#blogposting\",\"name\":\"Dice il proverbio \\u201cChi per bugiardo \\u00e8 conosciuto\\u2026\\u201d Sentiremo mai la verit\\u00e0 prima o poi? - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)\",\"headline\":\"Dice il proverbio &#8220;Chi per bugiardo \\u00e8 conosciuto&#8230;&#8221; Sentiremo mai la verit\\u00e0 prima o poi?\",\"author\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/author\\\/cambiamento\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.ilcambiamento.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/risposta-sindaco-1-impianti-sportivi-1.jpg?fit=940%2C1348&ssl=1\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\\\/#articleImage\",\"width\":940,\"height\":1348},\"datePublished\":\"2026-01-28T08:36:30+01:00\",\"dateModified\":\"2026-01-28T08:36:54+01:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\\\/#webpage\"},\"articleSection\":\"NEWS, bugie di frasson, Comune di Tombolo, impianti sportivi di tombolo, luca frasson\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/category\\\/home\\\/#listItem\",\"name\":\"HOME\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/category\\\/home\\\/#listItem\",\"position\":2,\"name\":\"HOME\",\"item\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/category\\\/home\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/category\\\/home\\\/news\\\/#listItem\",\"name\":\"NEWS\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/category\\\/home\\\/news\\\/#listItem\",\"position\":3,\"name\":\"NEWS\",\"item\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/category\\\/home\\\/news\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\\\/#listItem\",\"name\":\"Dice il proverbio &#8220;Chi per bugiardo \\u00e8 conosciuto&#8230;&#8221; Sentiremo mai la verit\\u00e0 prima o poi?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/category\\\/home\\\/#listItem\",\"name\":\"HOME\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\\\/#listItem\",\"position\":4,\"name\":\"Dice il proverbio &#8220;Chi per bugiardo \\u00e8 conosciuto&#8230;&#8221; Sentiremo mai la verit\\u00e0 prima o poi?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/category\\\/home\\\/news\\\/#listItem\",\"name\":\"NEWS\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/#organization\",\"name\":\"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)\",\"description\":\"Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...\",\"url\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.ilcambiamento.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/cropped-cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png?fit=150%2C149&ssl=1\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\\\/#organizationLogo\",\"width\":150,\"height\":149},\"image\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/civicailcambiamento\\\/\",\"https:\\\/\\\/www.instagram.com\\\/civica_il_cambiamento\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/author\\\/cambiamento\\\/#author\",\"url\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/author\\\/cambiamento\\\/\",\"name\":\"cambiamento\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/63138d16bdcd1bf80120e192040dbad60999ff237ea29c7fd1528ca692950461?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"cambiamento\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\\\/#webpage\",\"url\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\\\/\",\"name\":\"Dice il proverbio \\u201cChi per bugiardo \\u00e8 conosciuto\\u2026\\u201d Sentiremo mai la verit\\u00e0 prima o poi? - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)\",\"description\":\"Tombolo 26 gennaio 2026 Grazie all'interrogazione del nostro Gruppo anche stavolta il Sindaco viene clamorosamente smentito. Ogni volta lo stesso comunica alla cittadinanza come gli eventi siano rapidi ed improvvisi e non preventivabili. Anche su questa materia invece gli eventi erano non solo prevedibili, ma gi\\u00e0 divenuti gravi fin dal 2021 come emerge dalla risposta\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/author\\\/cambiamento\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/author\\\/cambiamento\\\/#author\"},\"datePublished\":\"2026-01-28T08:36:30+01:00\",\"dateModified\":\"2026-01-28T08:36:54+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/\",\"name\":\"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)\",\"description\":\"Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Dice il proverbio \u201cChi per bugiardo \u00e8 conosciuto\u2026\u201d Sentiremo mai la verit\u00e0 prima o poi? - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","description":"Tombolo 26 gennaio 2026 Grazie all'interrogazione del nostro Gruppo anche stavolta il Sindaco viene clamorosamente smentito. Ogni volta lo stesso comunica alla cittadinanza come gli eventi siano rapidi ed improvvisi e non preventivabili. Anche su questa materia invece gli eventi erano non solo prevedibili, ma gi\u00e0 divenuti gravi fin dal 2021 come emerge dalla risposta","canonical_url":"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/#blogposting","name":"Dice il proverbio \u201cChi per bugiardo \u00e8 conosciuto\u2026\u201d Sentiremo mai la verit\u00e0 prima o poi? - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","headline":"Dice il proverbio &#8220;Chi per bugiardo \u00e8 conosciuto&#8230;&#8221; Sentiremo mai la verit\u00e0 prima o poi?","author":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/author\/cambiamento\/#author"},"publisher":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2026\/01\/risposta-sindaco-1-impianti-sportivi-1.jpg?fit=940%2C1348&ssl=1","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/#articleImage","width":940,"height":1348},"datePublished":"2026-01-28T08:36:30+01:00","dateModified":"2026-01-28T08:36:54+01:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/#webpage"},"isPartOf":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/#webpage"},"articleSection":"NEWS, bugie di frasson, Comune di Tombolo, impianti sportivi di tombolo, luca frasson"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress#listItem","position":1,"name":"Home","item":"https:\/\/www.ilcambiamento.org\/wordpress","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/category\/home\/#listItem","name":"HOME"}},{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/category\/home\/#listItem","position":2,"name":"HOME","item":"https:\/\/www.ilcambiamento.org\/wordpress\/category\/home\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/category\/home\/news\/#listItem","name":"NEWS"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/category\/home\/news\/#listItem","position":3,"name":"NEWS","item":"https:\/\/www.ilcambiamento.org\/wordpress\/category\/home\/news\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/#listItem","name":"Dice il proverbio &#8220;Chi per bugiardo \u00e8 conosciuto&#8230;&#8221; Sentiremo mai la verit\u00e0 prima o poi?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/category\/home\/#listItem","name":"HOME"}},{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/#listItem","position":4,"name":"Dice il proverbio &#8220;Chi per bugiardo \u00e8 conosciuto&#8230;&#8221; Sentiremo mai la verit\u00e0 prima o poi?","previousItem":{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/category\/home\/news\/#listItem","name":"NEWS"}}]},{"@type":"Organization","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/#organization","name":"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","description":"Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...","url":"https:\/\/www.ilcambiamento.org\/wordpress\/","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png?fit=150%2C149&ssl=1","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/#organizationLogo","width":150,"height":149},"image":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/civicailcambiamento\/","https:\/\/www.instagram.com\/civica_il_cambiamento\/"]},{"@type":"Person","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/author\/cambiamento\/#author","url":"https:\/\/www.ilcambiamento.org\/wordpress\/author\/cambiamento\/","name":"cambiamento","image":{"@type":"ImageObject","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/63138d16bdcd1bf80120e192040dbad60999ff237ea29c7fd1528ca692950461?s=96&d=mm&r=g","width":96,"height":96,"caption":"cambiamento"}},{"@type":"WebPage","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/#webpage","url":"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/","name":"Dice il proverbio \u201cChi per bugiardo \u00e8 conosciuto\u2026\u201d Sentiremo mai la verit\u00e0 prima o poi? - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","description":"Tombolo 26 gennaio 2026 Grazie all'interrogazione del nostro Gruppo anche stavolta il Sindaco viene clamorosamente smentito. Ogni volta lo stesso comunica alla cittadinanza come gli eventi siano rapidi ed improvvisi e non preventivabili. Anche su questa materia invece gli eventi erano non solo prevedibili, ma gi\u00e0 divenuti gravi fin dal 2021 come emerge dalla risposta","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/#website"},"breadcrumb":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/#breadcrumblist"},"author":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/author\/cambiamento\/#author"},"creator":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/author\/cambiamento\/#author"},"datePublished":"2026-01-28T08:36:30+01:00","dateModified":"2026-01-28T08:36:54+01:00"},{"@type":"WebSite","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/#website","url":"https:\/\/www.ilcambiamento.org\/wordpress\/","name":"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","description":"Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/#organization"}}]},"og:locale":"it_IT","og:site_name":"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD) - Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...","og:type":"article","og:title":"Dice il proverbio \u201cChi per bugiardo \u00e8 conosciuto\u2026\u201d Sentiremo mai la verit\u00e0 prima o poi? - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","og:description":"Tombolo 26 gennaio 2026 Grazie all'interrogazione del nostro Gruppo anche stavolta il Sindaco viene clamorosamente smentito. Ogni volta lo stesso comunica alla cittadinanza come gli eventi siano rapidi ed improvvisi e non preventivabili. Anche su questa materia invece gli eventi erano non solo prevedibili, ma gi\u00e0 divenuti gravi fin dal 2021 come emerge dalla risposta","og:url":"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/","og:image":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png","og:image:secure_url":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png","og:image:width":150,"og:image:height":150,"article:published_time":"2026-01-28T07:36:30+00:00","article:modified_time":"2026-01-28T07:36:54+00:00","article:publisher":"https:\/\/www.facebook.com\/civicailcambiamento\/","twitter:card":"summary_large_image","twitter:title":"Dice il proverbio \u201cChi per bugiardo \u00e8 conosciuto\u2026\u201d Sentiremo mai la verit\u00e0 prima o poi? - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","twitter:description":"Tombolo 26 gennaio 2026 Grazie all'interrogazione del nostro Gruppo anche stavolta il Sindaco viene clamorosamente smentito. Ogni volta lo stesso comunica alla cittadinanza come gli eventi siano rapidi ed improvvisi e non preventivabili. Anche su questa materia invece gli eventi erano non solo prevedibili, ma gi\u00e0 divenuti gravi fin dal 2021 come emerge dalla risposta","twitter:image":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png"},"aioseo_meta_data":{"post_id":"2821","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-01-28 07:36:54","updated":"2026-01-28 07:42:45","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ilcambiamento.org\/wordpress\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ilcambiamento.org\/wordpress\/category\/home\/\" title=\"HOME\">HOME<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ilcambiamento.org\/wordpress\/category\/home\/news\/\" title=\"NEWS\">NEWS<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDice il proverbio \u201cChi per bugiardo \u00e8 conosciuto\u2026\u201d Sentiremo mai la verit\u00e0 prima o poi?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.ilcambiamento.org\/wordpress"},{"label":"HOME","link":"https:\/\/www.ilcambiamento.org\/wordpress\/category\/home\/"},{"label":"NEWS","link":"https:\/\/www.ilcambiamento.org\/wordpress\/category\/home\/news\/"},{"label":"Dice il proverbio &#8220;Chi per bugiardo \u00e8 conosciuto&#8230;&#8221; Sentiremo mai la verit\u00e0 prima o poi?","link":"https:\/\/www.ilcambiamento.org\/wordpress\/dice-il-proverbio-chi-per-bugiardo-e-conosciuto-sentiremo-mai-la-verita-prima-o-poi\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p5PPUp-Jv","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/posts\/2821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/comments?post=2821"}],"version-history":[{"count":1,"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/posts\/2821\/revisions"}],"predecessor-version":[{"id":2831,"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/posts\/2821\/revisions\/2831"}],"wp:attachment":[{"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/media?parent=2821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/categories?post=2821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/tags?post=2821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}