{"id":2377,"date":"2024-05-20T08:30:44","date_gmt":"2024-05-20T06:30:44","guid":{"rendered":"https:\/\/www.ilcambiamento.org\/wordpress\/?page_id=2377"},"modified":"2024-05-20T08:58:17","modified_gmt":"2024-05-20T06:58:17","slug":"nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento","status":"publish","type":"page","link":"https:\/\/www.ilcambiamento.org\/wordpress\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\/","title":{"rendered":"NUOVO PARCHEGGIO NEL POLO SCOLASTICO: il progetto della Civica IL CAMBIAMENTO"},"content":{"rendered":"\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1235\" height=\"1210\" src=\"https:\/\/i2.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/05\/area-acquisiata-scuola-1.png?fit=700%2C686&amp;ssl=1\" alt=\"\" class=\"wp-image-2379\" srcset=\"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/05\/area-acquisiata-scuola-1.png?w=1235&amp;ssl=1 1235w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/05\/area-acquisiata-scuola-1.png?resize=300%2C294&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/05\/area-acquisiata-scuola-1.png?resize=768%2C752&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/05\/area-acquisiata-scuola-1.png?resize=1024%2C1003&amp;ssl=1 1024w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/05\/area-acquisiata-scuola-1.png?resize=240%2C235&amp;ssl=1 240w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/05\/progetto-PARK-parcheggio-polo-scolastico.pdf\">Siamo pronti alla realizzazione: scarica il progetto del nuovo parcheggio! FATTI NON PAROLE!<\/a><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Siamo pronti alla realizzazione: scarica il progetto del nuovo parcheggio! FATTI NON PAROLE!<\/p>\n","protected":false},"author":5,"featured_media":2379,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"footnotes":""},"class_list":["post-2377","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Siamo pronti alla realizzazione: scarica il progetto del nuovo parcheggio! FATTI NON PAROLE!\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.ilcambiamento.org\/wordpress\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD) - Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"NUOVO PARCHEGGIO NEL POLO SCOLASTICO: il progetto della Civica IL CAMBIAMENTO - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)\" \/>\n\t\t<meta property=\"og:description\" content=\"Siamo pronti alla realizzazione: scarica il progetto del nuovo parcheggio! FATTI NON PAROLE!\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.ilcambiamento.org\/wordpress\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-05-20T06:30:44+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-05-20T06:58:17+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/civicailcambiamento\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"NUOVO PARCHEGGIO NEL POLO SCOLASTICO: il progetto della Civica IL CAMBIAMENTO - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Siamo pronti alla realizzazione: scarica il progetto del nuovo parcheggio! FATTI NON PAROLE!\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\\\/#listItem\",\"name\":\"NUOVO PARCHEGGIO NEL POLO SCOLASTICO: il progetto della Civica IL CAMBIAMENTO\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\\\/#listItem\",\"position\":2,\"name\":\"NUOVO PARCHEGGIO NEL POLO SCOLASTICO: il progetto della Civica IL CAMBIAMENTO\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/#organization\",\"name\":\"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)\",\"description\":\"Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...\",\"url\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.ilcambiamento.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/cropped-cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png?fit=150%2C149&ssl=1\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\\\/#organizationLogo\",\"width\":150,\"height\":149},\"image\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/civicailcambiamento\\\/\",\"https:\\\/\\\/www.instagram.com\\\/civica_il_cambiamento\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\\\/#webpage\",\"url\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\\\/\",\"name\":\"NUOVO PARCHEGGIO NEL POLO SCOLASTICO: il progetto della Civica IL CAMBIAMENTO - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)\",\"description\":\"Siamo pronti alla realizzazione: scarica il progetto del nuovo parcheggio! FATTI NON PAROLE!\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.ilcambiamento.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/area-acquisiata-scuola-1.png?fit=1235%2C1210&ssl=1\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\\\/#mainImage\",\"width\":1235,\"height\":1210},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\\\/#mainImage\"},\"datePublished\":\"2024-05-20T08:30:44+02:00\",\"dateModified\":\"2024-05-20T08:58:17+02:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/\",\"name\":\"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)\",\"description\":\"Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"NUOVO PARCHEGGIO NEL POLO SCOLASTICO: il progetto della Civica IL CAMBIAMENTO - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","description":"Siamo pronti alla realizzazione: scarica il progetto del nuovo parcheggio! FATTI NON PAROLE!","canonical_url":"https:\/\/www.ilcambiamento.org\/wordpress\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress#listItem","position":1,"name":"Home","item":"https:\/\/www.ilcambiamento.org\/wordpress","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\/#listItem","name":"NUOVO PARCHEGGIO NEL POLO SCOLASTICO: il progetto della Civica IL CAMBIAMENTO"}},{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\/#listItem","position":2,"name":"NUOVO PARCHEGGIO NEL POLO SCOLASTICO: il progetto della Civica IL CAMBIAMENTO","previousItem":{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/#organization","name":"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","description":"Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...","url":"https:\/\/www.ilcambiamento.org\/wordpress\/","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png?fit=150%2C149&ssl=1","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\/#organizationLogo","width":150,"height":149},"image":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/civicailcambiamento\/","https:\/\/www.instagram.com\/civica_il_cambiamento\/"]},{"@type":"WebPage","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\/#webpage","url":"https:\/\/www.ilcambiamento.org\/wordpress\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\/","name":"NUOVO PARCHEGGIO NEL POLO SCOLASTICO: il progetto della Civica IL CAMBIAMENTO - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","description":"Siamo pronti alla realizzazione: scarica il progetto del nuovo parcheggio! FATTI NON PAROLE!","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/#website"},"breadcrumb":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/05\/area-acquisiata-scuola-1.png?fit=1235%2C1210&ssl=1","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\/#mainImage","width":1235,"height":1210},"primaryImageOfPage":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\/#mainImage"},"datePublished":"2024-05-20T08:30:44+02:00","dateModified":"2024-05-20T08:58:17+02:00"},{"@type":"WebSite","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/#website","url":"https:\/\/www.ilcambiamento.org\/wordpress\/","name":"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","description":"Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/#organization"}}]},"og:locale":"it_IT","og:site_name":"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD) - Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...","og:type":"article","og:title":"NUOVO PARCHEGGIO NEL POLO SCOLASTICO: il progetto della Civica IL CAMBIAMENTO - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","og:description":"Siamo pronti alla realizzazione: scarica il progetto del nuovo parcheggio! FATTI NON PAROLE!","og:url":"https:\/\/www.ilcambiamento.org\/wordpress\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\/","og:image":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png","og:image:secure_url":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png","og:image:width":150,"og:image:height":150,"article:published_time":"2024-05-20T06:30:44+00:00","article:modified_time":"2024-05-20T06:58:17+00:00","article:publisher":"https:\/\/www.facebook.com\/civicailcambiamento\/","twitter:card":"summary_large_image","twitter:title":"NUOVO PARCHEGGIO NEL POLO SCOLASTICO: il progetto della Civica IL CAMBIAMENTO - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","twitter:description":"Siamo pronti alla realizzazione: scarica il progetto del nuovo parcheggio! FATTI NON PAROLE!","twitter:image":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png"},"aioseo_meta_data":{"post_id":"2377","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-09-29 11:02:50","updated":"2025-09-29 11:02:50","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ilcambiamento.org\/wordpress\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tNUOVO PARCHEGGIO NEL POLO SCOLASTICO: il progetto della Civica IL CAMBIAMENTO\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.ilcambiamento.org\/wordpress"},{"label":"NUOVO PARCHEGGIO NEL POLO SCOLASTICO: il progetto della Civica IL CAMBIAMENTO","link":"https:\/\/www.ilcambiamento.org\/wordpress\/nuovo-parcheggio-nel-polo-scolastico-il-progetto-della-civica-il-cambiamento\/"}],"jetpack_shortlink":"https:\/\/wp.me\/P5PPUp-Cl","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/pages\/2377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/comments?post=2377"}],"version-history":[{"count":2,"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/pages\/2377\/revisions"}],"predecessor-version":[{"id":2382,"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/pages\/2377\/revisions\/2382"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/media\/2379"}],"wp:attachment":[{"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/media?parent=2377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}