{"id":2289,"date":"2024-04-02T14:50:16","date_gmt":"2024-04-02T12:50:16","guid":{"rendered":"https:\/\/www.ilcambiamento.org\/wordpress\/?page_id=2289"},"modified":"2026-03-01T19:13:17","modified_gmt":"2026-03-01T18:13:17","slug":"la-squadra-2","status":"publish","type":"page","link":"https:\/\/www.ilcambiamento.org\/wordpress\/la-squadra-2\/","title":{"rendered":"La Squadra"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Se sei interessato a sapere di pi\u00f9 di Franco Zorzo &#8230; <a href=\"https:\/\/www.ilcambiamento.org\/wordpress\/franco-zorzo\/\" target=\"_blank\" rel=\"noopener\" title=\"\">clicca qui<\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"725\" height=\"1024\" src=\"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/03\/Schermata-2024-03-27-alle-19.11.07.png?resize=725%2C1024&#038;ssl=1\" alt=\"\" class=\"wp-image-2296\" srcset=\"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/03\/Schermata-2024-03-27-alle-19.11.07.png?resize=725%2C1024&amp;ssl=1 725w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/03\/Schermata-2024-03-27-alle-19.11.07.png?resize=212%2C300&amp;ssl=1 212w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/03\/Schermata-2024-03-27-alle-19.11.07.png?resize=768%2C1085&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/03\/Schermata-2024-03-27-alle-19.11.07.png?resize=170%2C240&amp;ssl=1 170w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/03\/Schermata-2024-03-27-alle-19.11.07.png?w=996&amp;ssl=1 996w\" sizes=\"auto, (max-width: 725px) 100vw, 725px\" \/><\/figure>\n<\/div>\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default aligncenter wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image\"><a href=\"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/03\/Schermata-2024-03-27-alle-16.52.48.png?ssl=1\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"623\" data-id=\"2291\" src=\"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/03\/Schermata-2024-03-27-alle-16.52.48.png?resize=740%2C623&#038;ssl=1\" alt=\"\" class=\"wp-image-2291\" srcset=\"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/03\/Schermata-2024-03-27-alle-16.52.48.png?w=997&amp;ssl=1 997w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/03\/Schermata-2024-03-27-alle-16.52.48.png?resize=300%2C253&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/03\/Schermata-2024-03-27-alle-16.52.48.png?resize=768%2C647&amp;ssl=1 768w, https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2024\/03\/Schermata-2024-03-27-alle-16.52.48.png?resize=240%2C202&amp;ssl=1 240w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/a><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Se sei interessato a sapere di pi\u00f9 di Franco Zorzo &#8230; clicca qui<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"ngg_post_thumbnail":0,"jetpack_post_was_ever_published":false,"footnotes":""},"class_list":["post-2289","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Se sei interessato a sapere di pi\u00f9 di Franco Zorzo ... clicca qui\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.ilcambiamento.org\/wordpress\/la-squadra-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD) - Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"La Squadra - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)\" \/>\n\t\t<meta property=\"og:description\" content=\"Se sei interessato a sapere di pi\u00f9 di Franco Zorzo ... clicca qui\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.ilcambiamento.org\/wordpress\/la-squadra-2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"150\" \/>\n\t\t<meta property=\"og:image:height\" content=\"150\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-04-02T12:50:16+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-03-01T18:13:17+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/civicailcambiamento\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"La Squadra - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Se sei interessato a sapere di pi\u00f9 di Franco Zorzo ... clicca qui\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/la-squadra-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/la-squadra-2\\\/#listItem\",\"name\":\"La Squadra\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/la-squadra-2\\\/#listItem\",\"position\":2,\"name\":\"La Squadra\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress#listItem\",\"name\":\"Home\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/#organization\",\"name\":\"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)\",\"description\":\"Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...\",\"url\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.ilcambiamento.org\\\/wordpress\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/cropped-cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png?fit=150%2C149&ssl=1\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/la-squadra-2\\\/#organizationLogo\",\"width\":150,\"height\":149},\"image\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/la-squadra-2\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/civicailcambiamento\\\/\",\"https:\\\/\\\/www.instagram.com\\\/civica_il_cambiamento\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/la-squadra-2\\\/#webpage\",\"url\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/la-squadra-2\\\/\",\"name\":\"La Squadra - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)\",\"description\":\"Se sei interessato a sapere di pi\\u00f9 di Franco Zorzo ... clicca qui\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/la-squadra-2\\\/#breadcrumblist\"},\"datePublished\":\"2024-04-02T14:50:16+02:00\",\"dateModified\":\"2026-03-01T19:13:17+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/#website\",\"url\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/\",\"name\":\"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)\",\"description\":\"Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ilcambiamento.org\\\/wordpress\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"La Squadra - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","description":"Se sei interessato a sapere di pi\u00f9 di Franco Zorzo ... clicca qui","canonical_url":"https:\/\/www.ilcambiamento.org\/wordpress\/la-squadra-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/la-squadra-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress#listItem","position":1,"name":"Home","item":"https:\/\/www.ilcambiamento.org\/wordpress","nextItem":{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/la-squadra-2\/#listItem","name":"La Squadra"}},{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/la-squadra-2\/#listItem","position":2,"name":"La Squadra","previousItem":{"@type":"ListItem","@id":"https:\/\/www.ilcambiamento.org\/wordpress#listItem","name":"Home"}}]},{"@type":"Organization","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/#organization","name":"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","description":"Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...","url":"https:\/\/www.ilcambiamento.org\/wordpress\/","logo":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png?fit=150%2C149&ssl=1","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/la-squadra-2\/#organizationLogo","width":150,"height":149},"image":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/la-squadra-2\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/civicailcambiamento\/","https:\/\/www.instagram.com\/civica_il_cambiamento\/"]},{"@type":"WebPage","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/la-squadra-2\/#webpage","url":"https:\/\/www.ilcambiamento.org\/wordpress\/la-squadra-2\/","name":"La Squadra - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","description":"Se sei interessato a sapere di pi\u00f9 di Franco Zorzo ... clicca qui","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/#website"},"breadcrumb":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/la-squadra-2\/#breadcrumblist"},"datePublished":"2024-04-02T14:50:16+02:00","dateModified":"2026-03-01T19:13:17+01:00"},{"@type":"WebSite","@id":"https:\/\/www.ilcambiamento.org\/wordpress\/#website","url":"https:\/\/www.ilcambiamento.org\/wordpress\/","name":"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","description":"Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...","inLanguage":"it-IT","publisher":{"@id":"https:\/\/www.ilcambiamento.org\/wordpress\/#organization"}}]},"og:locale":"it_IT","og:site_name":"CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD) - Una vera lista CIVICA per cambiare in meglio Tombolo ed Onara ...","og:type":"article","og:title":"La Squadra - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","og:description":"Se sei interessato a sapere di pi\u00f9 di Franco Zorzo ... clicca qui","og:url":"https:\/\/www.ilcambiamento.org\/wordpress\/la-squadra-2\/","og:image":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png","og:image:secure_url":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png","og:image:width":150,"og:image:height":150,"article:published_time":"2024-04-02T12:50:16+00:00","article:modified_time":"2026-03-01T18:13:17+00:00","article:publisher":"https:\/\/www.facebook.com\/civicailcambiamento\/","twitter:card":"summary_large_image","twitter:title":"La Squadra - CIVICA IL CAMBIAMENTO - Comune di Tombolo (PD)","twitter:description":"Se sei interessato a sapere di pi\u00f9 di Franco Zorzo ... clicca qui","twitter:image":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-content\/uploads\/2014\/03\/cropped-cropped-cambiamento_logo_GRANDE3-e1747828781946.png"},"aioseo_meta_data":{"post_id":"2289","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-09-29 11:02:02","updated":"2026-03-01 18:13:21","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.ilcambiamento.org\/wordpress\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tLa Squadra\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.ilcambiamento.org\/wordpress"},{"label":"La Squadra","link":"https:\/\/www.ilcambiamento.org\/wordpress\/la-squadra-2\/"}],"jetpack_shortlink":"https:\/\/wp.me\/P5PPUp-AV","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/pages\/2289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/comments?post=2289"}],"version-history":[{"count":9,"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/pages\/2289\/revisions"}],"predecessor-version":[{"id":2872,"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/pages\/2289\/revisions\/2872"}],"wp:attachment":[{"href":"https:\/\/www.ilcambiamento.org\/wordpress\/wp-json\/wp\/v2\/media?parent=2289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}